{"id":1880,"date":"2014-03-31T13:29:53","date_gmt":"2014-03-31T13:29:53","guid":{"rendered":"http:\/\/www.dhhn.de\/?p=1880"},"modified":"2018-08-27T06:40:44","modified_gmt":"2018-08-27T06:40:44","slug":"geduld-lernen-hilfstransport-nach-minsk","status":"publish","type":"post","link":"https:\/\/www.dhhn.de\/en\/geduld-lernen-hilfstransport-nach-minsk\/","title":{"rendered":"Geduld lernen &#8211; Hilfstransport nach Minsk"},"content":{"rendered":"<p>\u201eDas k\u00f6nnte doch mal wieder ein ganz normaler Hilfstransport werden\u201c war mein Gedanke, als ich sonntagmorgens auf recht leeren Autobahnen einen Lkw voller Hilfsg\u00fcter in den Osten fuhr. Ziel ist diesmal Minsk in Wei\u00dfrussland. Es ist eine sch\u00f6ne Fahrt, \u00fcber N\u00fcrnberg, Chemnitz und Dresden an die Deutsch-Polnische Grenze bei G\u00f6rlitz. Auch durch Polen geht es gut weiter. Hier hat die EU jede Menge neue Autobahnen gebaut, die man aber per Maut teuer bezahlen muss. Deshalb fahre ich nach wie vor die alten Landstra\u00dfen, die breit sind, aber kaum noch Verkehr haben. Quer durch Polen, ich komme an St\u00e4dten wie Breslau und Warschau vorbei. Gegen 16 komme ich an die Grenze nach Russland, und fahre an ca. 3km Lkw-Stau vorbei. Doch dann ist auch auf der zweiten Spur, die ich gerade nutze, eine Lkw Schlange. Noch 2km bis zur Grenze. Und durch einen Gefallen, den ich jemand mache, komme ich auf die innere Spur und kann die Schlange nicht mehr verlassen. Geduld \u00fcber ist angesagt.<\/p>\n<div id=\"attachment_1890\" style=\"width: 1040px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1890\" class=\"size-full wp-image-1890\" src=\"https:\/\/www.dhhn.de\/wp-content\/uploads\/2014\/03\/DHHN-9571.jpg\" alt=\"endlich vorne!\" width=\"1030\" height=\"400\" srcset=\"https:\/\/www.dhhn.de\/wp-content\/uploads\/2014\/03\/DHHN-9571.jpg 1030w, https:\/\/www.dhhn.de\/wp-content\/uploads\/2014\/03\/DHHN-9571-300x116.jpg 300w, https:\/\/www.dhhn.de\/wp-content\/uploads\/2014\/03\/DHHN-9571-705x273.jpg 705w, https:\/\/www.dhhn.de\/wp-content\/uploads\/2014\/03\/DHHN-9571-450x174.jpg 450w\" sizes=\"auto, (max-width: 1030px) 100vw, 1030px\" \/><p id=\"caption-attachment-1890\" class=\"wp-caption-text\">endlich vorne!<\/p><\/div>\n<p>Gegen 20 Uhr komme ich an die Grenze. Hier auf polnischer Seite klappt es sehr gut und schnell, schon nach 10 Minuten geht\u2019s weiter. Vor mir geht die Stra\u00dfe ca. 3km, eingerahmt von einem gr\u00fcnen Stahlzaun, bis zur eigentlichen Landesgrenze. Und ab dort von der Br\u00fccke den Bug bis zum Zollhof verbringe ich weitere 3-4 Stunden. Geduld \u00fcben ist angesagt. Im Zoll nimmt dann alles seinen gewohnten Gang. Und siehe da, es gibt keine Probleme! Keine Nachfragen, keine fehlenden Papiere, kein Androhen von Abladen, kein R\u00f6ntgen. Alles nimmt seinen Gang und so kann ich um 4 Uhr morgens Ortszeit nach Wei\u00dfrussland einreisen.<\/p>\n<p>Direkt nach der Grenze \u201e\u00fcbernachte\u201c ich dann auf einem bewachten Parkplatz, der zu der Werkstatt geh\u00f6rt, die mir im Sommer die Hydraulikleitung geflickt hatte. Am sp\u00e4ten Vormittag geht\u2019s weiter: Erstes Projekt: Eine Beltoll Mautbox kaufen. Dort erfahre ich, wie ich auch schon wusste, dass Hilfstransporte von der Maut befreit sind. Ich hatte mir extra im Vorfeld einen Antrag aus dem Internet heruntergeladen und ausgef\u00fcllt, und gab diesen dort ab. Das brachte die Leute aus dem Konzept. Hier anrufen, dort anrufen\u2026 Keiner konnte deutsch oder englisch\u2026 So mache ich ihnen mit Hilfe eines anderen Fahrers klar, dass ich einfach so eine Box kaufen m\u00f6chte und dann sp\u00e4ter den Mautbefreiungsantrag in Minsk abgeben werde. Antwort: Jetzt k\u00f6nnen sie mir keine Box mehr verkaufen\u2026 Na gut denke ich, fahre ich halt zur n\u00e4chsten Tankstelle und kaufe dort eine Box. Doch es kommt keine Tankstelle mit beltoll Service mehr. Da mir das alles ziemlich merkw\u00fcrdig vorkommt, halte ich bei einem Polizeiauto an und frage dort. Die bringen mich zu einem anderen Polizeiauto, und dort kennt man sich etwas mehr aus: Ich m\u00fcsse 520\u20ac Strafe bezahlen, da ich ohne Beltoll- Box unter zwei Mautbr\u00fccken durchgefahren bin. Alles Diskutieren bringt nichts. Im Prospekt, den ich vorher erhalten habe, steht schwarz auf wei\u00df, dass Hilfstransporte von der Maut befreit sind. Egal. Telefonate mit dem Empf\u00e4nger in Minsk \u00e4ndern auch nichts. Nach ca. 4 Stunden kann ich dann die Strafe direkt im Polizeiauto mit Visakarte bezahlen\u2026<\/p>\n<div id=\"attachment_1887\" style=\"width: 1040px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1887\" class=\"size-full wp-image-1887\" src=\"https:\/\/www.dhhn.de\/wp-content\/uploads\/2014\/03\/DHHN-9577.jpg\" alt=\"\u00c4rger mit Beltoll, Hilfstransporte sind von der Maut befreit. Nur keiner wei\u00df, wie!\" width=\"1030\" height=\"400\" srcset=\"https:\/\/www.dhhn.de\/wp-content\/uploads\/2014\/03\/DHHN-9577.jpg 1030w, https:\/\/www.dhhn.de\/wp-content\/uploads\/2014\/03\/DHHN-9577-300x116.jpg 300w, https:\/\/www.dhhn.de\/wp-content\/uploads\/2014\/03\/DHHN-9577-705x273.jpg 705w, https:\/\/www.dhhn.de\/wp-content\/uploads\/2014\/03\/DHHN-9577-450x174.jpg 450w\" sizes=\"auto, (max-width: 1030px) 100vw, 1030px\" \/><p id=\"caption-attachment-1887\" class=\"wp-caption-text\">\u00c4rger mit Beltoll, Hilfstransporte sind von der Maut befreit. Nur keiner wei\u00df, wie!<\/p><\/div>\n<p>Igor, unser Kontaktmann in Minsk, macht mir Hoffnung, dass ich das Geld zur\u00fcckbekomme. Mein Fall ist einfach im System nicht bedacht worden, so erkl\u00e4rte es ihm der Polizist. Der wiederum auch keine andere M\u00f6glichkeit hatte, da alles automatisch im Computer aufgezeichnet war\u2026<\/p>\n<p>Nun, so konnte ich dann zur n\u00e4chsten Beltoll-Servicestelle fahren und dort eine Box kaufen. Der arme Verk\u00e4ufer war ziemlich \u00fcberfordert mit seinem Computer, gemeinsam haben wir es dann innerhalb einer Stunde geschafft. Acht Unterschriften und ich hatte die legend\u00e4re Box endlich in meinen H\u00e4nden!<\/p>\n<p>Noch 350km bis Minsk, leider muss ich in der Dunkelheit fahren, was ich dort im Osten nur sehr ungern mache. Doch ich muss am n\u00e4chsten Morgen am Zoll sein, sonst l\u00e4uft die Frist ab. Alles geht gut und ich habe eine ruhige Nacht auf dem Zollhof. Am n\u00e4chsten Morgen geht der Zoll an Blitzschnell. Keine halbe Stunde, und wir k\u00f6nnen schon zum Abladen. Das einzig kuriose: Ich muss noch eine Bescheinigung organisieren, wie lange das mitgebrachte Sp\u00fclmittel haltbar ist.<\/p>\n<p>Nun geht\u2019s quer durch die Stadt zum Invalidenverein. Wie immer, alles zugeparkt. Wieder Geduld \u00fcben, nach 1,5 Stunden f\u00fcr 70 Meter bin ich endlich am Ziel. Igor kommt mit 10 Mann von der Rehastation und so wird der Lkw abgeladen. Alle sind mit Eifer dabei, und so leert sich der Lkw und das Lager wird immer voller. Die Organisatorinnen vom Invalidenverein strahlen \u00fcbers ganze Gesicht und freuen sich \u00fcber all die G\u00fcter, die sie weitergeben k\u00f6nnen.<\/p>\n<p>W\u00e4hrend der Lkw noch abgeladen wir besuche ich mit Igor das Rehazentrum. Es ist sch\u00f6n zu sehen, wie es sich weiterentwickelt und wie Menschen frei von Drogen und Alkohol werden.<\/p>\n<div id=\"attachment_1912\" style=\"width: 1040px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1912\" class=\"size-full wp-image-1912\" src=\"https:\/\/www.dhhn.de\/wp-content\/uploads\/2014\/03\/DHHN-9673.jpg\" alt=\"Igor und Oleg fahren mit mir zum Rehazentrum\" width=\"1030\" height=\"400\" srcset=\"https:\/\/www.dhhn.de\/wp-content\/uploads\/2014\/03\/DHHN-9673.jpg 1030w, https:\/\/www.dhhn.de\/wp-content\/uploads\/2014\/03\/DHHN-9673-300x116.jpg 300w, https:\/\/www.dhhn.de\/wp-content\/uploads\/2014\/03\/DHHN-9673-705x273.jpg 705w, https:\/\/www.dhhn.de\/wp-content\/uploads\/2014\/03\/DHHN-9673-450x174.jpg 450w\" sizes=\"auto, (max-width: 1030px) 100vw, 1030px\" \/><p id=\"caption-attachment-1912\" class=\"wp-caption-text\">Igor und Oleg fahren mit mir zum Rehazentrum<\/p><\/div>\n<p>Am fr\u00fchen Nachmittag geht\u2019s dann wieder gen Westen. Mit vollen Tanks, hier kostet der Diesel nur knapp 0,80\u20ac, geht\u2019s zur litauischen Grenze. Denn nur hier darf der Tank voll sein. 13 Kilometer vor der Grenze f\u00e4ngt der Lkw-Stau an. Ich fahre z\u00fcgig vorbei, werde dann aber von mehreren Fahrern, die mitten auf der Stra\u00dfe stehen, angehalten. Nach einer recht ruhigen Diskussion darf ich weiter fahren und komme direkt bis vor den Schlagbaum. Hier ist z\u00e4hes diskutieren mit dem Grenzpolizisten angesagt, nach ca. einer Stunde darf ich dann in den Zollhof. Im Zoll sind rund 30 Fahrer, die vor vier Schaltern, wovon zwei besetzt sind,\u00a0 stehen. Ich gehe an einen Schalter vor und erkl\u00e4re den Fahrern dort, dass ich Hilfsg\u00fcter zum Invalidenverein gebracht habe und ob ich denn vor darf. Jetzt geht das Gezeter los: Ich sei doch leer und deshalb kein Hilfstransport mehr. Und \u00fcberhaupt. Zum Gl\u00fcck verstehe ich kein russisch, aber das Geschrei ist gro\u00df und dem Tonfall nach zu urteilen sind sie nicht sehr begeistert von mir. Ich frage sie dann auf Deutsch, ob sie denn Egoisten sein wollen. Ich komme aus Deutschland und bringe ihren Invaliden Hilfe. Ein paar werden ruhiger, aber die R\u00e4delsf\u00fchrer bleiben bei ihrer lautstark vertretenen Meinung: Sobald der Lkw leer ist, ist es kein Hilfstransport mehr. Nun denn, ich stelle mich etwas seitlich hin und warte mal ab. Theoretisch sind 20 Mann vor mir dran, wie man anhand der nummerierten Laufzettel erkennen kann. 20 Mann a mind. 10 Minuten\u2026<\/p>\n<p>Tats\u00e4chlich h\u00e4lt sich aber keiner so richtig an die Nummern\u2026 Die Diskussion \u00fcber mich hat sich in die linke Seite des Raumes verlagert, ich stehe rechts alleine. Und pl\u00f6tzlich wird der Schalter direkt vor mir frei. Und ich bin der einzige, der dort steht und das merkt. Ich z\u00f6ger kurz, doch die Z\u00f6llnerin sagt dawai und ich gebe meine Papiere rein. Es brauchte keine Minute, und die anderen haben es auch bemerkt und kommen lautstark schreiend her. Ich mache ihnen Platz und sie reden auf die Beamtin ein. Die sagt irgendeinen Satz zur\u00fcck und alle sind friedlich. Vielleicht sollt ich mir den Satz mal aufschreiben lassen! J<\/p>\n<p>Und jetzt ist es endlich soweit: Mein Gedanke von der Abfahrt erf\u00fcllt sich. Ab jetzt wird es eine ganze normale R\u00fcckreise, ohne irgendwelche Probleme. \u00dcber Vilnius, Kaunas, Suwalki, Warschau, Breslau komme ich wieder nach Deutschland. Und am Sonntagabend bin ich wieder dankbar und gl\u00fccklich zu Hause.<\/p>\n<article  class='iconbox iconbox_left av-6vlhk-7833d4a6112fbf97027f9c995c98a30b  avia-builder-el-0  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: Viele weitere Bilder!\"><div class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue80e' data-av_iconfont='entypo-fontello' title=\"Viele weitere Bilder!\" desc=\"Viele weitere Bilder!\" ><\/div><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.dhhn.de\/en\/fahrtenbuch-2\/bilder-hilfstransport-minsk-2014\/' title='Viele weitere Bilder!'  >Viele weitere Bilder!<\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><p>Hier finden Sie noch weitere Bilder von diesem Hilfstransport nach Minsk\/Wei\u00dfrussland.<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article>\n","protected":false},"excerpt":{"rendered":"<p>\u201eDas k\u00f6nnte doch mal wieder ein ganz normaler Hilfstransport werden\u201c war mein Gedanke, als ich sonntagmorgens auf recht leeren Autobahnen einen Lkw voller Hilfsg\u00fcter in den Osten fuhr. Ziel ist diesmal Minsk in Wei\u00dfrussland. Es ist eine sch\u00f6ne Fahrt, \u00fcber N\u00fcrnberg, Chemnitz und Dresden an die Deutsch-Polnische Grenze bei G\u00f6rlitz. Auch durch Polen geht es [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1891,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.dhhn.de\/en\/wp-json\/wp\/v2\/posts\/1880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dhhn.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dhhn.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dhhn.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dhhn.de\/en\/wp-json\/wp\/v2\/comments?post=1880"}],"version-history":[{"count":9,"href":"https:\/\/www.dhhn.de\/en\/wp-json\/wp\/v2\/posts\/1880\/revisions"}],"predecessor-version":[{"id":11860,"href":"https:\/\/www.dhhn.de\/en\/wp-json\/wp\/v2\/posts\/1880\/revisions\/11860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dhhn.de\/en\/wp-json\/wp\/v2\/media\/1891"}],"wp:attachment":[{"href":"https:\/\/www.dhhn.de\/en\/wp-json\/wp\/v2\/media?parent=1880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dhhn.de\/en\/wp-json\/wp\/v2\/categories?post=1880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dhhn.de\/en\/wp-json\/wp\/v2\/tags?post=1880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}